{"id":336,"date":"2016-06-10T12:02:25","date_gmt":"2016-06-10T12:02:25","guid":{"rendered":"https:\/\/vezoinstituto.com.br\/blog\/?p=336"},"modified":"2016-06-10T12:02:25","modified_gmt":"2016-06-10T12:02:25","slug":"trabalho-manual-agrega-valor-e-salva-exportacoes-de-malhas-no-sul-de-mg","status":"publish","type":"post","link":"https:\/\/vezoinstituto.com.br\/blog\/2016\/06\/10\/trabalho-manual-agrega-valor-e-salva-exportacoes-de-malhas-no-sul-de-mg\/","title":{"rendered":"Trabalho manual agrega valor e salva exporta\u00e7\u00f5es de malhas no Sul de MG"},"content":{"rendered":"<div class=\"7434be6837f2faf7fb84d58c35337d7c\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Meio postagem1 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:320px;height:100px\"\r\n     data-ad-client=\"ca-pub-4083846062789388\"\r\n     data-ad-slot=\"3054367358\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<div class=\"materia-titulo\">\n<p>No in\u00edcio dos anos 2000, Jacutinga tinha 30 exportadores no segmento.\u00a0Empres\u00e1ria d\u00e1 receita e conta como conseguiu se manter no topo.<\/p>\n<\/div>\n<div class=\"materia-assinatura-letra\">\n<div class=\"materia-assinatura\">\n<p class=\"vcard author\"><strong>por Daniela Ayres\u00a0<span class=\"adr\"><span class=\"locality\">Do G1 Sul de Minas<\/span><\/span>\u00a0<\/strong><\/p>\n<\/div>\n<\/div>\n<div id=\"materia-letra\" class=\"materia-conteudo entry-content clearfix\">\n<p>Todos os meses, cerca de 10 mil pe\u00e7as assinadas pela estilista Cec\u00edlia Prado saem da confec\u00e7\u00e3o de propriedade de sua fam\u00edlia em Jacutinga\u00a0(MG). Pelo menos 75% da produ\u00e7\u00e3o \u00e9 exportada para vendas no atacado dos Estados Unidos, \u00c1sia, Europa e Oriente M\u00e9dio. Quando a empresa decidiu se arriscar no exterior, no in\u00edcio dos anos 2000, outras 30 malharias da cidade fizeram o mesmo investimento. Quinze anos depois, apenas a marca de Cec\u00edlia permaneceu, conforme a Associa\u00e7\u00e3o Comercial e Industrial de Jacutinga. As exporta\u00e7\u00f5es, que j\u00e1 chegaram a 15% das vendas na cidade, hoje representam apenas 3%.<\/p>\n<div class=\"foto componente_materia midia-largura-300\"><img fetchpriority=\"high\" decoding=\"async\" class=\" alignleft\" title=\"Cec\u00edlia com um dos modelos de sua marca: identidade de Jacutinga, MG, para o mundo (Foto: Daniela Ayres\/ G1)\" src=\"http:\/\/s2.glbimg.com\/g8ue9LM0VKlPxl9FWP4mHRtz8Vg=\/300x225\/s.glbimg.com\/jo\/g1\/f\/original\/2016\/06\/07\/61.jpg\" alt=\"Cec\u00edlia com um dos modelos de sua marca: identidade de Jacutinga, MG, para o mundo (Foto: Daniela Ayres\/ G1)\" width=\"300\" height=\"225\" \/><strong>Cec\u00edlia com um dos modelos de sua marca:<br \/>\nidentidade de Jacutinga, MG, para o mundo<br \/>\n(Foto: Daniela Ayres\/ G1)<\/strong><\/div>\n<p>Atualmente com 100 funcion\u00e1rios, a malharia come\u00e7ou pequena, em princ\u00edpios dos anos 1980. O foco era o p\u00fablico local, mas j\u00e1 com o esp\u00edrito de produzir modelos \u00fanicos que identificassem sua origem. A m\u00e3e de Cec\u00edlia e Louren\u00e7o, Yara Prado, tamb\u00e9m era estilista. O conceito de moda como pe\u00e7as que possuem valor agregado parece ter facilitado o caminho que o empreendimento trilhou fora do pa\u00eds.<\/p>\n<p>&#8220;O cliente, quando v\u00ea a pe\u00e7a, j\u00e1 sabe que \u00e9 nossa&#8221;, orgulha-se Cec\u00edlia. &#8220;Ao longo desses anos, fizemos nosso caminho. Nossa ess\u00eancia \u00e9 muito forte, temos um produto muito caracter\u00edstico, super autoral. Temos um longo caminho a percorrer, mas j\u00e1 temos um certo nome l\u00e1 fora.&#8221;<\/p>\n<div class=\"foto componente_materia midia-largura-620\"><img decoding=\"async\" class=\" alignleft\" title=\"\u00danica exportadora de moda em malharia de Jacutinga, MG, confec\u00e7\u00e3o tem hoje 100 funcion\u00e1rios (Foto: Daniela Ayres\/ G1)\" src=\"http:\/\/s2.glbimg.com\/vJ1jWY0cdTlPBcqL4B8ijW7OHCg=\/s.glbimg.com\/jo\/g1\/f\/original\/2016\/06\/07\/60.jpg\" alt=\"\u00danica exportadora de moda em malharia de Jacutinga, MG, confec\u00e7\u00e3o tem hoje 100 funcion\u00e1rios (Foto: Daniela Ayres\/ G1)\" width=\"620\" height=\"465\" \/><strong>\u00danica exportadora de moda em malharia de Jacutinga, MG, confec\u00e7\u00e3o tem hoje 100 funcion\u00e1rios<br \/>\n(Foto: Daniela Ayres\/ G1)<\/strong><\/div>\n<p>Cada modelo &#8211; em geral, casacos, vestidos, biqu\u00ednis &#8211; tem um detalhe produzido manualmente. Um vestido chega a ser vendido nos Estados Unidos por 800 d\u00f3lares. A cria\u00e7\u00e3o e a transforma\u00e7\u00e3o em um produto resultam de um trabalho mais lento do que o feito por malharias especializadas em produ\u00e7\u00f5es em s\u00e9rie. Para Louren\u00e7o, \u00e9 o que faz a empresa continuar atrativa para estrangeiros, mesmo com oscila\u00e7\u00f5es no c\u00e2mbio e o aumento da competi\u00e7\u00e3o.<\/p>\n<p>&#8220;Procuramos conhecer o nosso p\u00fablico. Apanhamos muito no come\u00e7o, com calotes de clientes, tivemos pe\u00e7as copiadas, trabalhamos com o c\u00e2mbio apertado &#8211; porque com o d\u00f3lar a R$ 1,50 n\u00e3o d\u00e1 para ter uma margem alta [de lucro]. Leva de cinco anos a uma d\u00e9cada para se estabelecer no mercado como marca confi\u00e1vel, que entrega na data certa, com a qualidade certa. E hoje mostramos isso para o cliente e com roupas que t\u00eam muito DNA, o que \u00e9 essencial. Se tem um segredo, \u00e9 persist\u00eancia&#8221;, aponta o diretor comercial.<\/p>\n<div class=\"foto componente_materia midia-largura-620\"><img decoding=\"async\" class=\" aligncenter\" title=\"Al\u00e9m da persist\u00eancia, empres\u00e1rios procurarm imprimir um estilo pr\u00f3prio, com trabalhos manuais, nas pe\u00e7as em malhas de tric\u00f4; Jacutinga, MG (Foto: Daniela Ayres\/ G1)\" src=\"http:\/\/s2.glbimg.com\/0QfH2U-aEjOoa5MsjQHLU33NhQg=\/s.glbimg.com\/jo\/g1\/f\/original\/2016\/06\/07\/58.jpg\" alt=\"Al\u00e9m da persist\u00eancia, empres\u00e1rios procurarm imprimir um estilo pr\u00f3prio, com trabalhos manuais, nas pe\u00e7as em malhas de tric\u00f4; Jacutinga, MG (Foto: Daniela Ayres\/ G1)\" width=\"620\" height=\"465\" \/><\/div>\n<p><strong>Exemplo para o mercado local<\/strong><br \/>\nDe olho nesse caso de sucesso, a Acija (Associa\u00e7\u00e3o Comercial e Industrial de Jacutinga) tem buscado meios para que mais empresas da cidade se tornem exportadora de moda.<\/p>\n<div class=\"foto componente_materia midia-largura-300\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft\" title=\"Jacutinga, MG, \u00e9 considerado um dos polos t\u00eaxteis do Brasil; cidade possui pelo 1,2 mil confec\u00e7\u00f5es (Foto: Daniela Ayres\/ G1)\" src=\"http:\/\/s2.glbimg.com\/jc20wkY5HxYZOECTgAgNrfg8A-k=\/300x225\/s.glbimg.com\/jo\/g1\/f\/original\/2016\/06\/07\/69.jpg\" alt=\"Jacutinga, MG, \u00e9 considerado um dos polos t\u00eaxteis do Brasil; cidade possui pelo 1,2 mil confec\u00e7\u00f5es (Foto: Daniela Ayres\/ G1)\" width=\"300\" height=\"225\" \/><strong>Jacutinga \u00e9 considerado um dos polos t\u00eaxteis<br \/>\ndo Brasil; cidade possui pelo 1,2 mil confec\u00e7\u00f5es<br \/>\n(Foto: Daniela Ayres\/ G1)<\/strong><\/div>\n<p>&#8220;As exporta\u00e7\u00f5es j\u00e1 representaram cerca de 15% das nossas vendas. Hoje correspondem a 3%. Houve uma perda de foco, em parte devido ao d\u00f3lar&#8221;, aponta o presidente da Acija, Dennys Bandeira, lembrando o per\u00edodo em que o d\u00f3lar operou em alta no pa\u00eds.<\/p>\n<p>&#8220;Estamos em busca de incentivo para ganhar de novo espa\u00e7o fora do pa\u00eds porque temos esse potencial, com uma produ\u00e7\u00e3o que possui identidade&#8221;, avalia.<\/p>\n<p>Respondendo por 30% da produ\u00e7\u00e3o nacional de malhas, Jacutinga \u00e9 considerada um dos p\u00f3los t\u00eaxteis do Brasil com pelo menos 1,2 mil f\u00e1bricas e 750 lojas no segmento. Por ano, a cidade, com popula\u00e7\u00e3o estimada em 24.930 habitantes, produz 30 milh\u00f5es de pe\u00e7as com malhas de tric\u00f4.<\/p>\n<p>Virg\u00edlio de Oliveira Prado Neto \u00e9 um dos empres\u00e1rios que j\u00e1 tentou a sorte no exterior e pensa em retomar o investimento. H\u00e1 30 anos, ele e a esposa criaram uma marca que hoje coloca no mercado cerca de 5 mil pe\u00e7as de roupas por m\u00eas.<\/p>\n<div class=\"foto componente_materia midia-largura-620\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft\" title=\"Apesar de tentativas para exportar, confec\u00e7\u00e3o de Virg\u00edlio investiu em tecnologia e pesquisa para enfrentar chegada de chineses ao mercado brasileiro (Foto: Daniela Ayres\/ G1)\" src=\"http:\/\/s2.glbimg.com\/hejS5R1vKnK-1yAF65SusNY4TOs=\/s.glbimg.com\/jo\/g1\/f\/original\/2016\/06\/07\/80.jpg\" alt=\"Apesar de tentativas para exportar, confec\u00e7\u00e3o de Virg\u00edlio investiu em tecnologia e pesquisa para enfrentar chegada de chineses ao mercado brasileiro (Foto: Daniela Ayres\/ G1)\" width=\"620\" height=\"465\" \/><strong>Apesar de tentativas para exportar, confec\u00e7\u00e3o de Virg\u00edlio investiu em tecnologia e pesquisa para enfrentar chegada de chineses ao mercado brasileiro (Foto: Daniela Ayres\/ G1)<\/strong><\/div>\n<p>&#8220;Come\u00e7amos como uma oficininha de fundo de quintal mesmo, em 1986. Fomos crescendo ano a ano e fizemos parte de tr\u00eas cons\u00f3rcios para vender nossos produtos no exterior&#8221;, recorda Virg\u00edlio. &#8220;Foi muito trabalhosa essa iniciativa. Tivemos que fazer prospec\u00e7\u00e3o na Europa inteira, praticamente, nos pa\u00edses da Am\u00e9rica Central e at\u00e9 na Am\u00e9rica do Norte. Mas, logo que a gente iniciou as vendas, acabou o apoio [log\u00edstico e financeiro]. N\u00e3o dava para fazer cada um sozinho.&#8221;<\/p>\n<p>Na \u00e9poca, o apoio basicamente vinha de uma entidade de iniciativa privada liga ao setor t\u00eaxtil, mas contava tamb\u00e9m com investimento governamental. Segundo o empres\u00e1rio, ele sentiu que houve uma mudan\u00e7a na pol\u00edtica de incentivo a f\u00e1bricas como a dele, o que, aliado \u00e0 abertura do mercado brasileiro aos produtos chineses, teria desestimulado a investida internacional. A sa\u00edda foi apostar em pesquisa e tecnologia para garantir espa\u00e7o em solo brasileiro.<\/p>\n<p><a href=\"http:\/\/artemodacursos.com.br\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-250\" src=\"https:\/\/vezoinstituto.com.br\/blog\/wp-content\/uploads\/2016\/05\/PROPAGANDA2.png\" alt=\"PROPAGANDA\" width=\"500\" height=\"200\" \/><\/a><\/p>\n<div class=\"foto componente_materia midia-largura-300\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft\" title=\"Pe\u00e7as da confecc\u00e3o de Virg\u00edlio representam marcas brasileiras e tamb\u00e9m pelo Brasil com a marca de Jacutinga, MG (Foto: Daniela Ayres\/ G1)\" src=\"http:\/\/s2.glbimg.com\/ieDjVXO23hzLroVWVUftxTqoaqc=\/300x225\/s.glbimg.com\/jo\/g1\/f\/original\/2016\/06\/07\/24.jpg\" alt=\"Pe\u00e7as da confecc\u00e3o de Virg\u00edlio representam marcas brasileiras e tamb\u00e9m pelo Brasil com a marca de Jacutinga, MG (Foto: Daniela Ayres\/ G1)\" width=\"300\" height=\"225\" \/><\/div>\n<p>&#8220;A partir de 2005, os chineses chegaram com muita voracidade. A gente se preocupou mais em defender o nosso mercado e encontrou a sa\u00edda no private label [modelo de neg\u00f3cio em que se produz para outra marca], com empresas nacionais. Hoje, 70% do que produzimos \u00e9 private label, \u00e9 o que paga as contas, e 30% t\u00eam a nossa identidade. Agora, com maior fiscaliza\u00e7\u00e3o do produto asi\u00e1tico e o c\u00e2mbio mais favor\u00e1vel, a gente come\u00e7a a pensar de novo em exporta\u00e7\u00e3o&#8221;, diz.<\/p>\n<p><strong>De rival a cliente<\/strong><br \/>\nCec\u00edlia concorda que os chineses podem se tornar concorrentes de peso no mercado t\u00eaxtil, mas com a trajet\u00f3ria tra\u00e7ada pela sua marca eles se tornaram clientes. Com moda praia e um mix das cole\u00e7\u00f5es, as vendas anuais para a China correspondem a 5% das exporta\u00e7\u00f5es da confec\u00e7\u00e3o.<\/p>\n<p>&#8220;A gente n\u00e3o sente tanto a cobran\u00e7a da China porque o nosso trabalho \u00e9 super autoral, dif\u00edcil, demorado&#8221;, explica, destacando que o caminho das pedras \u00e9 investir nos detalhes. &#8220;Se sair do padr\u00e3o, as chances de conquistar o p\u00fablico s\u00e3o maiores&#8221;, diz.<\/p>\n<div class=\"foto componente_materia midia-largura-620 on\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft\" title=\"Cec\u00edlia Prado mostra um dos modelos de sua cole\u00e7\u00e3o: vestidos chegam a ser vendidos a 800 d\u00f3lares nos EUA (Foto: Daniela Ayres\/ G1)\" src=\"http:\/\/s2.glbimg.com\/6peu__nI_tp3U75GsPpc5UZGuBI=\/s.glbimg.com\/jo\/g1\/f\/original\/2016\/06\/07\/62.jpg\" alt=\"Cec\u00edlia Prado mostra um dos modelos de sua cole\u00e7\u00e3o: vestidos chegam a ser vendidos a 800 d\u00f3lares nos EUA (Foto: Daniela Ayres\/ G1)\" width=\"620\" height=\"465\" \/><\/div>\n<p>No final de maio, a estilista se preparava para enviar 16 mil pe\u00e7as para os Estados Unidos, o principal comprador. A produ\u00e7\u00e3o de vestidos de festa, saias, cardigans, ponchos acompanhada de perto para garantir que tudo sa\u00edsse como um planejado. &#8220;Se a marca entra, sai, deu um probleminha, n\u00e3o vai para a feira, voc\u00ea n\u00e3o vai ter a credibilidade do cliente. Fa\u00e7a chuva, fa\u00e7a sol, voc\u00ea tem que estar a\u00ed, pode ter um prejuizinho, mas n\u00e3o pode deixar a peteca cair&#8221;, aconselha.<\/p>\n<p>&#8220;Nos primeiros anos, as exporta\u00e7\u00f5es representavam 5% das nossas vendas. Quando a gente foi exportar pela primeira vez, conhecer o mercado, a gente foi em uma feira em Paris junto com umas 30 malharias da regi\u00e3o. Na segunda edi\u00e7\u00e3o, sobraram 15. E assim at\u00e9 que s\u00f3 a gente ficou. A gente tinha um projeto e, mesmo com dificuldade, nunca pensou em desistir&#8221;, garante Louren\u00e7o.<\/p>\n<div class=\"foto componente_materia midia-largura-620\"><img loading=\"lazy\" decoding=\"async\" class=\" alignleft\" title=\"Para Louren\u00e7o e Cec\u00edlia, exportar significa conhecer o p\u00fablico e n\u00e3o deixar a 'peteca cair' (Foto: Daniela Ayres\/ G1)\" src=\"http:\/\/s2.glbimg.com\/GIMBKCiG6rDGJDNiN3APUoUueKE=\/s.glbimg.com\/jo\/g1\/f\/original\/2016\/06\/07\/54.jpg\" alt=\"Para Louren\u00e7o e Cec\u00edlia, exportar significa conhecer o p\u00fablico e n\u00e3o deixar a 'peteca cair' (Foto: Daniela Ayres\/ G1)\" width=\"620\" height=\"465\" \/><strong>Para Louren\u00e7o e Cec\u00edlia, exportar significa conhecer o p\u00fablico e n\u00e3o deixar a &#8216;peteca cair&#8217;<br \/>\n(Foto: Daniela Ayres\/ G1)<\/strong><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\"><\/div>\n<div class=\"foto componente_materia midia-largura-620\">Fonte: G1 Sul de Minas<\/div>\n<\/div>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>No in\u00edcio dos anos 2000, Jacutinga tinha 30 exportadores no segmento.\u00a0Empres\u00e1ria d\u00e1 receita e conta como conseguiu se manter no topo. por Daniela Ayres\u00a0Do G1 Sul de Minas\u00a0 Todos os meses, cerca de 10 mil pe\u00e7as assinadas pela estilista Cec\u00edlia&#8230; <a class=\"more-link\" href=\"https:\/\/vezoinstituto.com.br\/blog\/2016\/06\/10\/trabalho-manual-agrega-valor-e-salva-exportacoes-de-malhas-no-sul-de-mg\/\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas"],"_links":{"self":[{"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/wp\/v2\/posts\/336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/wp\/v2\/comments?post=336"}],"version-history":[{"count":0,"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/wp\/v2\/posts\/336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/wp\/v2\/media?parent=336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/wp\/v2\/categories?post=336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vezoinstituto.com.br\/blog\/wp-json\/wp\/v2\/tags?post=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}